{"id":6164,"date":"2020-05-13T12:24:37","date_gmt":"2020-05-13T11:24:37","guid":{"rendered":"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/05\/husbil-husvagn-sticker-familj-itineo.jpeg"},"modified":"2020-05-13T12:45:45","modified_gmt":"2020-05-13T11:45:45","slug":"husbil-husvagn-sticker-familj-itineo","status":"inherit","type":"attachment","link":"https:\/\/blog.originalpeople.com\/sv\/2024\/10\/12\/designa-vinyldekaler\/husbil-husvagn-sticker-familj-itineo\/","title":{"rendered":"husbil-husvagn-sticker-familj-itineo"},"author":10,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>husbil-husvagn-sticker-familj-itineo - Originalpeople<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.originalpeople.com\/sv\/2024\/10\/12\/designa-vinyldekaler\/husbil-husvagn-sticker-familj-itineo\/\" \/>\n<meta property=\"og:locale\" content=\"sv_SE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"husbil-husvagn-sticker-familj-itineo - Originalpeople\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.originalpeople.com\/sv\/2024\/10\/12\/designa-vinyldekaler\/husbil-husvagn-sticker-familj-itineo\/\" \/>\n<meta property=\"og:site_name\" content=\"Originalpeople\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-13T11:45:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/05\/husbil-husvagn-sticker-familj-itineo.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1873\" \/>\n\t<meta property=\"og:image:height\" content=\"1873\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/blog.originalpeople.com\/sv\/2024\/10\/12\/designa-vinyldekaler\/husbil-husvagn-sticker-familj-itineo\/\",\"url\":\"https:\/\/blog.originalpeople.com\/sv\/2024\/10\/12\/designa-vinyldekaler\/husbil-husvagn-sticker-familj-itineo\/\",\"name\":\"husbil-husvagn-sticker-familj-itineo - Originalpeople\",\"isPartOf\":{\"@id\":\"https:\/\/blog.originalpeople.com\/es\/#website\"},\"datePublished\":\"2020-05-13T11:24:37+00:00\",\"dateModified\":\"2020-05-13T11:45:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/blog.originalpeople.com\/sv\/2024\/10\/12\/designa-vinyldekaler\/husbil-husvagn-sticker-familj-itineo\/#breadcrumb\"},\"inLanguage\":\"sv-SE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blog.originalpeople.com\/sv\/2024\/10\/12\/designa-vinyldekaler\/husbil-husvagn-sticker-familj-itineo\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blog.originalpeople.com\/sv\/2024\/10\/12\/designa-vinyldekaler\/husbil-husvagn-sticker-familj-itineo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/blog.originalpeople.com\/sv\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Designa vinyldekaler\",\"item\":\"https:\/\/blog.originalpeople.com\/sv\/2024\/10\/12\/designa-vinyldekaler\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"husbil-husvagn-sticker-familj-itineo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blog.originalpeople.com\/es\/#website\",\"url\":\"https:\/\/blog.originalpeople.com\/es\/\",\"name\":\"Originalpeople\",\"description\":\"Where you design personal sticker decals!\",\"publisher\":{\"@id\":\"https:\/\/blog.originalpeople.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blog.originalpeople.com\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"sv-SE\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/blog.originalpeople.com\/es\/#organization\",\"name\":\"Originalpeople\",\"url\":\"https:\/\/blog.originalpeople.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sv-SE\",\"@id\":\"https:\/\/blog.originalpeople.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2016\/10\/oplogo-color-250x56-1.png\",\"contentUrl\":\"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2016\/10\/oplogo-color-250x56-1.png\",\"width\":250,\"height\":56,\"caption\":\"Originalpeople\"},\"image\":{\"@id\":\"https:\/\/blog.originalpeople.com\/es\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"husbil-husvagn-sticker-familj-itineo - Originalpeople","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.originalpeople.com\/sv\/2024\/10\/12\/designa-vinyldekaler\/husbil-husvagn-sticker-familj-itineo\/","og_locale":"sv_SE","og_type":"article","og_title":"husbil-husvagn-sticker-familj-itineo - Originalpeople","og_url":"https:\/\/blog.originalpeople.com\/sv\/2024\/10\/12\/designa-vinyldekaler\/husbil-husvagn-sticker-familj-itineo\/","og_site_name":"Originalpeople","article_modified_time":"2020-05-13T11:45:45+00:00","og_image":[{"width":1873,"height":1873,"url":"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/05\/husbil-husvagn-sticker-familj-itineo.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/blog.originalpeople.com\/sv\/2024\/10\/12\/designa-vinyldekaler\/husbil-husvagn-sticker-familj-itineo\/","url":"https:\/\/blog.originalpeople.com\/sv\/2024\/10\/12\/designa-vinyldekaler\/husbil-husvagn-sticker-familj-itineo\/","name":"husbil-husvagn-sticker-familj-itineo - Originalpeople","isPartOf":{"@id":"https:\/\/blog.originalpeople.com\/es\/#website"},"datePublished":"2020-05-13T11:24:37+00:00","dateModified":"2020-05-13T11:45:45+00:00","breadcrumb":{"@id":"https:\/\/blog.originalpeople.com\/sv\/2024\/10\/12\/designa-vinyldekaler\/husbil-husvagn-sticker-familj-itineo\/#breadcrumb"},"inLanguage":"sv-SE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.originalpeople.com\/sv\/2024\/10\/12\/designa-vinyldekaler\/husbil-husvagn-sticker-familj-itineo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/blog.originalpeople.com\/sv\/2024\/10\/12\/designa-vinyldekaler\/husbil-husvagn-sticker-familj-itineo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.originalpeople.com\/sv\/"},{"@type":"ListItem","position":2,"name":"Designa vinyldekaler","item":"https:\/\/blog.originalpeople.com\/sv\/2024\/10\/12\/designa-vinyldekaler\/"},{"@type":"ListItem","position":3,"name":"husbil-husvagn-sticker-familj-itineo"}]},{"@type":"WebSite","@id":"https:\/\/blog.originalpeople.com\/es\/#website","url":"https:\/\/blog.originalpeople.com\/es\/","name":"Originalpeople","description":"Where you design personal sticker decals!","publisher":{"@id":"https:\/\/blog.originalpeople.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.originalpeople.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"sv-SE"},{"@type":"Organization","@id":"https:\/\/blog.originalpeople.com\/es\/#organization","name":"Originalpeople","url":"https:\/\/blog.originalpeople.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"sv-SE","@id":"https:\/\/blog.originalpeople.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2016\/10\/oplogo-color-250x56-1.png","contentUrl":"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2016\/10\/oplogo-color-250x56-1.png","width":250,"height":56,"caption":"Originalpeople"},"image":{"@id":"https:\/\/blog.originalpeople.com\/es\/#\/schema\/logo\/image\/"}}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/05\/husbil-husvagn-sticker-familj-itineo.jpeg'><img loading=\"lazy\" width=\"300\" height=\"300\" src=\"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/05\/husbil-husvagn-sticker-familj-itineo-300x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"dekaler till din husbil\/vagn\" decoding=\"async\" srcset=\"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/05\/husbil-husvagn-sticker-familj-itineo-300x300.jpeg 300w, https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/05\/husbil-husvagn-sticker-familj-itineo-1024x1024.jpeg 1024w, https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/05\/husbil-husvagn-sticker-familj-itineo-150x150.jpeg 150w, https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/05\/husbil-husvagn-sticker-familj-itineo-768x768.jpeg 768w, https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/05\/husbil-husvagn-sticker-familj-itineo-1536x1536.jpeg 1536w, https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/05\/husbil-husvagn-sticker-familj-itineo-1200x1200.jpeg 1200w, https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/05\/husbil-husvagn-sticker-familj-itineo.jpeg 1873w\" sizes=\"(max-width: 300px) 85vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"dekaler till din husbil\/vagn","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1873,"height":1873,"file":"2020\/05\/husbil-husvagn-sticker-familj-itineo.jpeg","sizes":{"medium":{"file":"husbil-husvagn-sticker-familj-itineo-300x300.jpeg","width":300,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/05\/husbil-husvagn-sticker-familj-itineo-300x300.jpeg"},"large":{"file":"husbil-husvagn-sticker-familj-itineo-1024x1024.jpeg","width":1024,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/05\/husbil-husvagn-sticker-familj-itineo-1024x1024.jpeg"},"thumbnail":{"file":"husbil-husvagn-sticker-familj-itineo-150x150.jpeg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/05\/husbil-husvagn-sticker-familj-itineo-150x150.jpeg"},"medium_large":{"file":"husbil-husvagn-sticker-familj-itineo-768x768.jpeg","width":768,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/05\/husbil-husvagn-sticker-familj-itineo-768x768.jpeg"},"1536x1536":{"file":"husbil-husvagn-sticker-familj-itineo-1536x1536.jpeg","width":1536,"height":1536,"mime_type":"image\/jpeg","source_url":"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/05\/husbil-husvagn-sticker-familj-itineo-1536x1536.jpeg"},"post-thumbnail":{"file":"husbil-husvagn-sticker-familj-itineo-1200x1200.jpeg","width":1200,"height":1200,"mime_type":"image\/jpeg","source_url":"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/05\/husbil-husvagn-sticker-familj-itineo-1200x1200.jpeg"},"full":{"file":"husbil-husvagn-sticker-familj-itineo.jpeg","width":1873,"height":1873,"mime_type":"image\/jpeg","source_url":"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/05\/husbil-husvagn-sticker-familj-itineo.jpeg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":6077,"source_url":"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/05\/husbil-husvagn-sticker-familj-itineo.jpeg","_links":{"self":[{"href":"https:\/\/blog.originalpeople.com\/sv\/wp-json\/wp\/v2\/media\/6164"}],"collection":[{"href":"https:\/\/blog.originalpeople.com\/sv\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/blog.originalpeople.com\/sv\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/blog.originalpeople.com\/sv\/wp-json\/wp\/v2\/users\/10"}]}}