{"id":12630,"date":"2022-03-18T12:11:59","date_gmt":"2022-03-18T11:11:59","guid":{"rendered":"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/05\/3-1.png"},"modified":"2022-03-18T12:11:59","modified_gmt":"2022-03-18T11:11:59","slug":"3-4","status":"inherit","type":"attachment","link":"https:\/\/blog.originalpeople.com\/sv\/2024\/10\/12\/designa-vinyldekaler\/3-4\/","title":{"rendered":"pergatinas_personalizadas"},"author":16,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>pergatinas_personalizadas - Originalpeople<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.originalpeople.com\/sv\/2024\/10\/12\/designa-vinyldekaler\/3-4\/\" \/>\n<meta property=\"og:locale\" content=\"sv_SE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"pergatinas_personalizadas - Originalpeople\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.originalpeople.com\/sv\/2024\/10\/12\/designa-vinyldekaler\/3-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Originalpeople\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/05\/3-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1620\" \/>\n\t<meta property=\"og:image:height\" content=\"1620\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/blog.originalpeople.com\/sv\/2024\/10\/12\/designa-vinyldekaler\/3-4\/\",\"url\":\"https:\/\/blog.originalpeople.com\/sv\/2024\/10\/12\/designa-vinyldekaler\/3-4\/\",\"name\":\"pergatinas_personalizadas - Originalpeople\",\"isPartOf\":{\"@id\":\"https:\/\/blog.originalpeople.com\/es\/#website\"},\"datePublished\":\"2022-03-18T11:11:59+00:00\",\"dateModified\":\"2022-03-18T11:11:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/blog.originalpeople.com\/sv\/2024\/10\/12\/designa-vinyldekaler\/3-4\/#breadcrumb\"},\"inLanguage\":\"sv-SE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blog.originalpeople.com\/sv\/2024\/10\/12\/designa-vinyldekaler\/3-4\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blog.originalpeople.com\/sv\/2024\/10\/12\/designa-vinyldekaler\/3-4\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/blog.originalpeople.com\/sv\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Designa vinyldekaler\",\"item\":\"https:\/\/blog.originalpeople.com\/sv\/2024\/10\/12\/designa-vinyldekaler\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"pergatinas_personalizadas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blog.originalpeople.com\/es\/#website\",\"url\":\"https:\/\/blog.originalpeople.com\/es\/\",\"name\":\"Originalpeople\",\"description\":\"Where you design personal sticker decals!\",\"publisher\":{\"@id\":\"https:\/\/blog.originalpeople.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blog.originalpeople.com\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"sv-SE\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/blog.originalpeople.com\/es\/#organization\",\"name\":\"Originalpeople\",\"url\":\"https:\/\/blog.originalpeople.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sv-SE\",\"@id\":\"https:\/\/blog.originalpeople.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2016\/10\/oplogo-color-250x56-1.png\",\"contentUrl\":\"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2016\/10\/oplogo-color-250x56-1.png\",\"width\":250,\"height\":56,\"caption\":\"Originalpeople\"},\"image\":{\"@id\":\"https:\/\/blog.originalpeople.com\/es\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"pergatinas_personalizadas - Originalpeople","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.originalpeople.com\/sv\/2024\/10\/12\/designa-vinyldekaler\/3-4\/","og_locale":"sv_SE","og_type":"article","og_title":"pergatinas_personalizadas - Originalpeople","og_url":"https:\/\/blog.originalpeople.com\/sv\/2024\/10\/12\/designa-vinyldekaler\/3-4\/","og_site_name":"Originalpeople","og_image":[{"width":1620,"height":1620,"url":"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/05\/3-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/blog.originalpeople.com\/sv\/2024\/10\/12\/designa-vinyldekaler\/3-4\/","url":"https:\/\/blog.originalpeople.com\/sv\/2024\/10\/12\/designa-vinyldekaler\/3-4\/","name":"pergatinas_personalizadas - Originalpeople","isPartOf":{"@id":"https:\/\/blog.originalpeople.com\/es\/#website"},"datePublished":"2022-03-18T11:11:59+00:00","dateModified":"2022-03-18T11:11:59+00:00","breadcrumb":{"@id":"https:\/\/blog.originalpeople.com\/sv\/2024\/10\/12\/designa-vinyldekaler\/3-4\/#breadcrumb"},"inLanguage":"sv-SE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.originalpeople.com\/sv\/2024\/10\/12\/designa-vinyldekaler\/3-4\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/blog.originalpeople.com\/sv\/2024\/10\/12\/designa-vinyldekaler\/3-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.originalpeople.com\/sv\/"},{"@type":"ListItem","position":2,"name":"Designa vinyldekaler","item":"https:\/\/blog.originalpeople.com\/sv\/2024\/10\/12\/designa-vinyldekaler\/"},{"@type":"ListItem","position":3,"name":"pergatinas_personalizadas"}]},{"@type":"WebSite","@id":"https:\/\/blog.originalpeople.com\/es\/#website","url":"https:\/\/blog.originalpeople.com\/es\/","name":"Originalpeople","description":"Where you design personal sticker decals!","publisher":{"@id":"https:\/\/blog.originalpeople.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.originalpeople.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"sv-SE"},{"@type":"Organization","@id":"https:\/\/blog.originalpeople.com\/es\/#organization","name":"Originalpeople","url":"https:\/\/blog.originalpeople.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"sv-SE","@id":"https:\/\/blog.originalpeople.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2016\/10\/oplogo-color-250x56-1.png","contentUrl":"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2016\/10\/oplogo-color-250x56-1.png","width":250,"height":56,"caption":"Originalpeople"},"image":{"@id":"https:\/\/blog.originalpeople.com\/es\/#\/schema\/logo\/image\/"}}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/05\/3-1.png'><img loading=\"lazy\" width=\"300\" height=\"300\" src=\"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/05\/3-1.png\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":1620,"height":1620,"file":"2020\/05\/3-1.png","sizes":{},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":6077,"source_url":"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/05\/3-1.png","_links":{"self":[{"href":"https:\/\/blog.originalpeople.com\/sv\/wp-json\/wp\/v2\/media\/12630"}],"collection":[{"href":"https:\/\/blog.originalpeople.com\/sv\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/blog.originalpeople.com\/sv\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/blog.originalpeople.com\/sv\/wp-json\/wp\/v2\/users\/16"}]}}