{"id":11830,"date":"2020-07-03T14:27:29","date_gmt":"2020-07-03T13:27:29","guid":{"rendered":"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/07\/adesivi-camper.jpeg"},"modified":"2020-07-03T14:27:29","modified_gmt":"2020-07-03T13:27:29","slug":"adesivi-camper-2","status":"inherit","type":"attachment","link":"https:\/\/blog.originalpeople.com\/sv\/2024\/10\/12\/designa-vinyldekaler\/adesivi-camper-2\/","title":{"rendered":"adesivi-camper"},"author":10,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>adesivi-camper - Originalpeople<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.originalpeople.com\/sv\/2024\/10\/12\/designa-vinyldekaler\/adesivi-camper-2\/\" \/>\n<meta property=\"og:locale\" content=\"sv_SE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"adesivi-camper - Originalpeople\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.originalpeople.com\/sv\/2024\/10\/12\/designa-vinyldekaler\/adesivi-camper-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Originalpeople\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/07\/adesivi-camper.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2304\" \/>\n\t<meta property=\"og:image:height\" content=\"2304\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/blog.originalpeople.com\/sv\/2024\/10\/12\/designa-vinyldekaler\/adesivi-camper-2\/\",\"url\":\"https:\/\/blog.originalpeople.com\/sv\/2024\/10\/12\/designa-vinyldekaler\/adesivi-camper-2\/\",\"name\":\"adesivi-camper - Originalpeople\",\"isPartOf\":{\"@id\":\"https:\/\/blog.originalpeople.com\/es\/#website\"},\"datePublished\":\"2020-07-03T13:27:29+00:00\",\"dateModified\":\"2020-07-03T13:27:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/blog.originalpeople.com\/sv\/2024\/10\/12\/designa-vinyldekaler\/adesivi-camper-2\/#breadcrumb\"},\"inLanguage\":\"sv-SE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blog.originalpeople.com\/sv\/2024\/10\/12\/designa-vinyldekaler\/adesivi-camper-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blog.originalpeople.com\/sv\/2024\/10\/12\/designa-vinyldekaler\/adesivi-camper-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/blog.originalpeople.com\/sv\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Designa vinyldekaler\",\"item\":\"https:\/\/blog.originalpeople.com\/sv\/2024\/10\/12\/designa-vinyldekaler\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"adesivi-camper\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blog.originalpeople.com\/es\/#website\",\"url\":\"https:\/\/blog.originalpeople.com\/es\/\",\"name\":\"Originalpeople\",\"description\":\"Where you design personal sticker decals!\",\"publisher\":{\"@id\":\"https:\/\/blog.originalpeople.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blog.originalpeople.com\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"sv-SE\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/blog.originalpeople.com\/es\/#organization\",\"name\":\"Originalpeople\",\"url\":\"https:\/\/blog.originalpeople.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sv-SE\",\"@id\":\"https:\/\/blog.originalpeople.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2016\/10\/oplogo-color-250x56-1.png\",\"contentUrl\":\"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2016\/10\/oplogo-color-250x56-1.png\",\"width\":250,\"height\":56,\"caption\":\"Originalpeople\"},\"image\":{\"@id\":\"https:\/\/blog.originalpeople.com\/es\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"adesivi-camper - Originalpeople","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.originalpeople.com\/sv\/2024\/10\/12\/designa-vinyldekaler\/adesivi-camper-2\/","og_locale":"sv_SE","og_type":"article","og_title":"adesivi-camper - Originalpeople","og_url":"https:\/\/blog.originalpeople.com\/sv\/2024\/10\/12\/designa-vinyldekaler\/adesivi-camper-2\/","og_site_name":"Originalpeople","og_image":[{"width":2304,"height":2304,"url":"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/07\/adesivi-camper.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/blog.originalpeople.com\/sv\/2024\/10\/12\/designa-vinyldekaler\/adesivi-camper-2\/","url":"https:\/\/blog.originalpeople.com\/sv\/2024\/10\/12\/designa-vinyldekaler\/adesivi-camper-2\/","name":"adesivi-camper - Originalpeople","isPartOf":{"@id":"https:\/\/blog.originalpeople.com\/es\/#website"},"datePublished":"2020-07-03T13:27:29+00:00","dateModified":"2020-07-03T13:27:29+00:00","breadcrumb":{"@id":"https:\/\/blog.originalpeople.com\/sv\/2024\/10\/12\/designa-vinyldekaler\/adesivi-camper-2\/#breadcrumb"},"inLanguage":"sv-SE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.originalpeople.com\/sv\/2024\/10\/12\/designa-vinyldekaler\/adesivi-camper-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/blog.originalpeople.com\/sv\/2024\/10\/12\/designa-vinyldekaler\/adesivi-camper-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.originalpeople.com\/sv\/"},{"@type":"ListItem","position":2,"name":"Designa vinyldekaler","item":"https:\/\/blog.originalpeople.com\/sv\/2024\/10\/12\/designa-vinyldekaler\/"},{"@type":"ListItem","position":3,"name":"adesivi-camper"}]},{"@type":"WebSite","@id":"https:\/\/blog.originalpeople.com\/es\/#website","url":"https:\/\/blog.originalpeople.com\/es\/","name":"Originalpeople","description":"Where you design personal sticker decals!","publisher":{"@id":"https:\/\/blog.originalpeople.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.originalpeople.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"sv-SE"},{"@type":"Organization","@id":"https:\/\/blog.originalpeople.com\/es\/#organization","name":"Originalpeople","url":"https:\/\/blog.originalpeople.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"sv-SE","@id":"https:\/\/blog.originalpeople.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2016\/10\/oplogo-color-250x56-1.png","contentUrl":"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2016\/10\/oplogo-color-250x56-1.png","width":250,"height":56,"caption":"Originalpeople"},"image":{"@id":"https:\/\/blog.originalpeople.com\/es\/#\/schema\/logo\/image\/"}}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/07\/adesivi-camper.jpeg'><img loading=\"lazy\" width=\"300\" height=\"300\" src=\"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/07\/adesivi-camper-300x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/07\/adesivi-camper-300x300.jpeg 300w, https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/07\/adesivi-camper-1024x1024.jpeg 1024w, https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/07\/adesivi-camper-150x150.jpeg 150w, https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/07\/adesivi-camper-768x768.jpeg 768w, https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/07\/adesivi-camper-1536x1536.jpeg 1536w, https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/07\/adesivi-camper-2048x2048.jpeg 2048w, https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/07\/adesivi-camper-1200x1200.jpeg 1200w\" sizes=\"(max-width: 300px) 85vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2304,"height":2304,"file":"2020\/07\/adesivi-camper.jpeg","sizes":{"medium":{"file":"adesivi-camper-300x300.jpeg","width":300,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/07\/adesivi-camper-300x300.jpeg"},"large":{"file":"adesivi-camper-1024x1024.jpeg","width":1024,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/07\/adesivi-camper-1024x1024.jpeg"},"thumbnail":{"file":"adesivi-camper-150x150.jpeg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/07\/adesivi-camper-150x150.jpeg"},"medium_large":{"file":"adesivi-camper-768x768.jpeg","width":768,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/07\/adesivi-camper-768x768.jpeg"},"1536x1536":{"file":"adesivi-camper-1536x1536.jpeg","width":1536,"height":1536,"mime_type":"image\/jpeg","source_url":"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/07\/adesivi-camper-1536x1536.jpeg"},"2048x2048":{"file":"adesivi-camper-2048x2048.jpeg","width":2048,"height":2048,"mime_type":"image\/jpeg","source_url":"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/07\/adesivi-camper-2048x2048.jpeg"},"post-thumbnail":{"file":"adesivi-camper-1200x1200.jpeg","width":1200,"height":1200,"mime_type":"image\/jpeg","source_url":"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/07\/adesivi-camper-1200x1200.jpeg"},"full":{"file":"adesivi-camper.jpeg","width":2304,"height":2304,"mime_type":"image\/jpeg","source_url":"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/07\/adesivi-camper.jpeg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":6077,"source_url":"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/07\/adesivi-camper.jpeg","_links":{"self":[{"href":"https:\/\/blog.originalpeople.com\/sv\/wp-json\/wp\/v2\/media\/11830"}],"collection":[{"href":"https:\/\/blog.originalpeople.com\/sv\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/blog.originalpeople.com\/sv\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/blog.originalpeople.com\/sv\/wp-json\/wp\/v2\/users\/10"}]}}