{"id":11238,"date":"2020-05-13T12:24:40","date_gmt":"2020-05-13T11:24:40","guid":{"rendered":"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/05\/sticker-par-dekal-grubs.png"},"modified":"2020-05-13T12:24:40","modified_gmt":"2020-05-13T11:24:40","slug":"sticker-par-dekal-grubs-2","status":"inherit","type":"attachment","link":"https:\/\/blog.originalpeople.com\/it\/2023\/01\/03\/adesivi-per-camper\/sticker-par-dekal-grubs-2\/","title":{"rendered":"sticker-par-dekal-grubs"},"author":10,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>sticker-par-dekal-grubs - Originalpeople<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.originalpeople.com\/it\/2023\/01\/03\/adesivi-per-camper\/sticker-par-dekal-grubs-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"sticker-par-dekal-grubs - Originalpeople\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.originalpeople.com\/it\/2023\/01\/03\/adesivi-per-camper\/sticker-par-dekal-grubs-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Originalpeople\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/05\/sticker-par-dekal-grubs.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/blog.originalpeople.com\/it\/2023\/01\/03\/adesivi-per-camper\/sticker-par-dekal-grubs-2\/\",\"url\":\"https:\/\/blog.originalpeople.com\/it\/2023\/01\/03\/adesivi-per-camper\/sticker-par-dekal-grubs-2\/\",\"name\":\"sticker-par-dekal-grubs - Originalpeople\",\"isPartOf\":{\"@id\":\"https:\/\/blog.originalpeople.com\/es\/#website\"},\"datePublished\":\"2020-05-13T11:24:40+00:00\",\"dateModified\":\"2020-05-13T11:24:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/blog.originalpeople.com\/it\/2023\/01\/03\/adesivi-per-camper\/sticker-par-dekal-grubs-2\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blog.originalpeople.com\/it\/2023\/01\/03\/adesivi-per-camper\/sticker-par-dekal-grubs-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blog.originalpeople.com\/it\/2023\/01\/03\/adesivi-per-camper\/sticker-par-dekal-grubs-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/blog.originalpeople.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adesivi per camper: un tocco originale e unico!\",\"item\":\"https:\/\/blog.originalpeople.com\/it\/2023\/01\/03\/adesivi-per-camper\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"sticker-par-dekal-grubs\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blog.originalpeople.com\/es\/#website\",\"url\":\"https:\/\/blog.originalpeople.com\/es\/\",\"name\":\"Originalpeople\",\"description\":\"Where you design personal sticker decals!\",\"publisher\":{\"@id\":\"https:\/\/blog.originalpeople.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blog.originalpeople.com\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/blog.originalpeople.com\/es\/#organization\",\"name\":\"Originalpeople\",\"url\":\"https:\/\/blog.originalpeople.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/blog.originalpeople.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2016\/10\/oplogo-color-250x56-1.png\",\"contentUrl\":\"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2016\/10\/oplogo-color-250x56-1.png\",\"width\":250,\"height\":56,\"caption\":\"Originalpeople\"},\"image\":{\"@id\":\"https:\/\/blog.originalpeople.com\/es\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"sticker-par-dekal-grubs - Originalpeople","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.originalpeople.com\/it\/2023\/01\/03\/adesivi-per-camper\/sticker-par-dekal-grubs-2\/","og_locale":"it_IT","og_type":"article","og_title":"sticker-par-dekal-grubs - Originalpeople","og_url":"https:\/\/blog.originalpeople.com\/it\/2023\/01\/03\/adesivi-per-camper\/sticker-par-dekal-grubs-2\/","og_site_name":"Originalpeople","og_image":[{"width":600,"height":600,"url":"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/05\/sticker-par-dekal-grubs.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/blog.originalpeople.com\/it\/2023\/01\/03\/adesivi-per-camper\/sticker-par-dekal-grubs-2\/","url":"https:\/\/blog.originalpeople.com\/it\/2023\/01\/03\/adesivi-per-camper\/sticker-par-dekal-grubs-2\/","name":"sticker-par-dekal-grubs - Originalpeople","isPartOf":{"@id":"https:\/\/blog.originalpeople.com\/es\/#website"},"datePublished":"2020-05-13T11:24:40+00:00","dateModified":"2020-05-13T11:24:40+00:00","breadcrumb":{"@id":"https:\/\/blog.originalpeople.com\/it\/2023\/01\/03\/adesivi-per-camper\/sticker-par-dekal-grubs-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.originalpeople.com\/it\/2023\/01\/03\/adesivi-per-camper\/sticker-par-dekal-grubs-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/blog.originalpeople.com\/it\/2023\/01\/03\/adesivi-per-camper\/sticker-par-dekal-grubs-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.originalpeople.com\/it\/"},{"@type":"ListItem","position":2,"name":"Adesivi per camper: un tocco originale e unico!","item":"https:\/\/blog.originalpeople.com\/it\/2023\/01\/03\/adesivi-per-camper\/"},{"@type":"ListItem","position":3,"name":"sticker-par-dekal-grubs"}]},{"@type":"WebSite","@id":"https:\/\/blog.originalpeople.com\/es\/#website","url":"https:\/\/blog.originalpeople.com\/es\/","name":"Originalpeople","description":"Where you design personal sticker decals!","publisher":{"@id":"https:\/\/blog.originalpeople.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.originalpeople.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/blog.originalpeople.com\/es\/#organization","name":"Originalpeople","url":"https:\/\/blog.originalpeople.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/blog.originalpeople.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2016\/10\/oplogo-color-250x56-1.png","contentUrl":"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2016\/10\/oplogo-color-250x56-1.png","width":250,"height":56,"caption":"Originalpeople"},"image":{"@id":"https:\/\/blog.originalpeople.com\/es\/#\/schema\/logo\/image\/"}}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/05\/sticker-par-dekal-grubs.png'><img loading=\"lazy\" width=\"300\" height=\"300\" src=\"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/05\/sticker-par-dekal-grubs-300x300.png\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/05\/sticker-par-dekal-grubs-300x300.png 300w, https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/05\/sticker-par-dekal-grubs-150x150.png 150w, https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/05\/sticker-par-dekal-grubs.png 600w\" sizes=\"(max-width: 300px) 85vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":600,"height":600,"file":"2020\/05\/sticker-par-dekal-grubs.png","sizes":{"medium":{"file":"sticker-par-dekal-grubs-300x300.png","width":300,"height":300,"mime_type":"image\/png","source_url":"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/05\/sticker-par-dekal-grubs-300x300.png"},"thumbnail":{"file":"sticker-par-dekal-grubs-150x150.png","width":150,"height":150,"mime_type":"image\/png","source_url":"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/05\/sticker-par-dekal-grubs-150x150.png"},"full":{"file":"sticker-par-dekal-grubs.png","width":600,"height":600,"mime_type":"image\/png","source_url":"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/05\/sticker-par-dekal-grubs.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":7055,"source_url":"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/05\/sticker-par-dekal-grubs.png","_links":{"self":[{"href":"https:\/\/blog.originalpeople.com\/it\/wp-json\/wp\/v2\/media\/11238"}],"collection":[{"href":"https:\/\/blog.originalpeople.com\/it\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/blog.originalpeople.com\/it\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/blog.originalpeople.com\/it\/wp-json\/wp\/v2\/users\/10"}]}}