{"id":11234,"date":"2020-05-13T12:24:39","date_gmt":"2020-05-13T11:24:39","guid":{"rendered":"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/05\/husvagn-dekal-hiking.png"},"modified":"2020-05-13T12:24:39","modified_gmt":"2020-05-13T11:24:39","slug":"husvagn-dekal-hiking-2","status":"inherit","type":"attachment","link":"https:\/\/blog.originalpeople.com\/es\/2024\/08\/20\/pegatinas-personalizadas\/husvagn-dekal-hiking-2\/","title":{"rendered":"husvagn-dekal-hiking"},"author":10,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>husvagn-dekal-hiking - Originalpeople<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.originalpeople.com\/es\/2024\/08\/20\/pegatinas-personalizadas\/husvagn-dekal-hiking-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"husvagn-dekal-hiking - Originalpeople\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.originalpeople.com\/es\/2024\/08\/20\/pegatinas-personalizadas\/husvagn-dekal-hiking-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Originalpeople\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/05\/husvagn-dekal-hiking.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/blog.originalpeople.com\/es\/2024\/08\/20\/pegatinas-personalizadas\/husvagn-dekal-hiking-2\/\",\"url\":\"https:\/\/blog.originalpeople.com\/es\/2024\/08\/20\/pegatinas-personalizadas\/husvagn-dekal-hiking-2\/\",\"name\":\"husvagn-dekal-hiking - Originalpeople\",\"isPartOf\":{\"@id\":\"https:\/\/blog.originalpeople.com\/es\/#website\"},\"datePublished\":\"2020-05-13T11:24:39+00:00\",\"dateModified\":\"2020-05-13T11:24:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/blog.originalpeople.com\/es\/2024\/08\/20\/pegatinas-personalizadas\/husvagn-dekal-hiking-2\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blog.originalpeople.com\/es\/2024\/08\/20\/pegatinas-personalizadas\/husvagn-dekal-hiking-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blog.originalpeople.com\/es\/2024\/08\/20\/pegatinas-personalizadas\/husvagn-dekal-hiking-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/blog.originalpeople.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pegatinas Personalizadas y Originales\",\"item\":\"https:\/\/blog.originalpeople.com\/es\/2024\/08\/20\/pegatinas-personalizadas\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"husvagn-dekal-hiking\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blog.originalpeople.com\/es\/#website\",\"url\":\"https:\/\/blog.originalpeople.com\/es\/\",\"name\":\"Originalpeople\",\"description\":\"Where you design personal sticker decals!\",\"publisher\":{\"@id\":\"https:\/\/blog.originalpeople.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blog.originalpeople.com\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/blog.originalpeople.com\/es\/#organization\",\"name\":\"Originalpeople\",\"url\":\"https:\/\/blog.originalpeople.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/blog.originalpeople.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2016\/10\/oplogo-color-250x56-1.png\",\"contentUrl\":\"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2016\/10\/oplogo-color-250x56-1.png\",\"width\":250,\"height\":56,\"caption\":\"Originalpeople\"},\"image\":{\"@id\":\"https:\/\/blog.originalpeople.com\/es\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"husvagn-dekal-hiking - Originalpeople","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.originalpeople.com\/es\/2024\/08\/20\/pegatinas-personalizadas\/husvagn-dekal-hiking-2\/","og_locale":"es_ES","og_type":"article","og_title":"husvagn-dekal-hiking - Originalpeople","og_url":"https:\/\/blog.originalpeople.com\/es\/2024\/08\/20\/pegatinas-personalizadas\/husvagn-dekal-hiking-2\/","og_site_name":"Originalpeople","og_image":[{"width":600,"height":200,"url":"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/05\/husvagn-dekal-hiking.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/blog.originalpeople.com\/es\/2024\/08\/20\/pegatinas-personalizadas\/husvagn-dekal-hiking-2\/","url":"https:\/\/blog.originalpeople.com\/es\/2024\/08\/20\/pegatinas-personalizadas\/husvagn-dekal-hiking-2\/","name":"husvagn-dekal-hiking - Originalpeople","isPartOf":{"@id":"https:\/\/blog.originalpeople.com\/es\/#website"},"datePublished":"2020-05-13T11:24:39+00:00","dateModified":"2020-05-13T11:24:39+00:00","breadcrumb":{"@id":"https:\/\/blog.originalpeople.com\/es\/2024\/08\/20\/pegatinas-personalizadas\/husvagn-dekal-hiking-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.originalpeople.com\/es\/2024\/08\/20\/pegatinas-personalizadas\/husvagn-dekal-hiking-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/blog.originalpeople.com\/es\/2024\/08\/20\/pegatinas-personalizadas\/husvagn-dekal-hiking-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.originalpeople.com\/es\/"},{"@type":"ListItem","position":2,"name":"Pegatinas Personalizadas y Originales","item":"https:\/\/blog.originalpeople.com\/es\/2024\/08\/20\/pegatinas-personalizadas\/"},{"@type":"ListItem","position":3,"name":"husvagn-dekal-hiking"}]},{"@type":"WebSite","@id":"https:\/\/blog.originalpeople.com\/es\/#website","url":"https:\/\/blog.originalpeople.com\/es\/","name":"Originalpeople","description":"Where you design personal sticker decals!","publisher":{"@id":"https:\/\/blog.originalpeople.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.originalpeople.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/blog.originalpeople.com\/es\/#organization","name":"Originalpeople","url":"https:\/\/blog.originalpeople.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blog.originalpeople.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2016\/10\/oplogo-color-250x56-1.png","contentUrl":"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2016\/10\/oplogo-color-250x56-1.png","width":250,"height":56,"caption":"Originalpeople"},"image":{"@id":"https:\/\/blog.originalpeople.com\/es\/#\/schema\/logo\/image\/"}}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/05\/husvagn-dekal-hiking.png'><img loading=\"lazy\" width=\"300\" height=\"100\" src=\"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/05\/husvagn-dekal-hiking-300x100.png\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/05\/husvagn-dekal-hiking-300x100.png 300w, https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/05\/husvagn-dekal-hiking.png 600w\" sizes=\"(max-width: 300px) 85vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":600,"height":200,"file":"2020\/05\/husvagn-dekal-hiking.png","sizes":{"medium":{"file":"husvagn-dekal-hiking-300x100.png","width":300,"height":100,"mime_type":"image\/png","source_url":"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/05\/husvagn-dekal-hiking-300x100.png"},"thumbnail":{"file":"husvagn-dekal-hiking-150x150.png","width":150,"height":150,"mime_type":"image\/png","source_url":"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/05\/husvagn-dekal-hiking-150x150.png"},"full":{"file":"husvagn-dekal-hiking.png","width":600,"height":200,"mime_type":"image\/png","source_url":"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/05\/husvagn-dekal-hiking.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":6410,"source_url":"https:\/\/blog.originalpeople.com\/wp-content\/uploads\/2020\/05\/husvagn-dekal-hiking.png","_links":{"self":[{"href":"https:\/\/blog.originalpeople.com\/es\/wp-json\/wp\/v2\/media\/11234"}],"collection":[{"href":"https:\/\/blog.originalpeople.com\/es\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/blog.originalpeople.com\/es\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/blog.originalpeople.com\/es\/wp-json\/wp\/v2\/users\/10"}]}}